{"id":654,"date":"2019-10-23T16:26:01","date_gmt":"2019-10-23T14:26:01","guid":{"rendered":"https:\/\/research.dii.unipd.it\/tecno\/?page_id=654"},"modified":"2023-12-20T15:03:38","modified_gmt":"2023-12-20T14:03:38","slug":"research-fellows-and-phd-st","status":"publish","type":"page","link":"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/","title":{"rendered":"Research Fellows and PhD St"},"content":{"rendered":"<div data-label=\"Team\" data-id=\"team--2\" data-export-id=\"team-4\" data-category=\"team\" class=\"team-4 content-section content-section-spacing\" id=\"team-2\" style=\"background-image: none\" data-section-ov=\"1\"><div class=\"gridContainer\"> <div class=\"row text-center\"><div class=\"section-title-col\" data-type=\"column\"> <h2 class=\"\" data-gramm=\"false\" data-quillbot-element=\"CqPLEKJ9LDyYH_krSV8zF\">PhD Students<\/h2> <\/div> <\/div> <div class=\"row spaced-cols content-center-sm\" data-type=\"row\">        <div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/10\/cropped-3-removebg-preview-1.png\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"cropped-3-removebg-preview-1.png\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Ali&nbsp;Beigzadeh\n<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">New technologies for smart and innovative production systems and materials<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/10\/cropped-Bonato_Nicolo.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"cropped-Bonato_Nicolo.jpg\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Nicol\u00f2 Bonato<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Enabling quality-enhanced advanced manufacturing by innovative metrological solutions<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/10\/cropped-cropped-kristal.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"cropped-cropped-kristal.jpg\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Kristal Bornilo<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Development of silicone-free prefilled plastic syringes by compression moulding of micro-structured surfaces<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/10\/cropped-C9255779-13A9-47AF-AB14-F0AD3406A0C4-scaled-1.jpeg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"C9255779-13A9-47AF-AB14-F0AD3406A0C4\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Anna Bortoletto<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Upcycling di polipropilene da raccolta differenziata urbana in una nuova generazione di compound ad alte prestazioni attraverso lo sviluppo di un sistema avanzato di produzione<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/12\/Bottin.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"Bottin\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Anna Bottin<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Geometrical and surface characterization of cutting tools and parts machined through innovative approaches<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/11\/Bovo.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"Bovo\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Enrico Bovo<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Development of Digital Twins for extrusion lines of PVC tubes<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/12\/Didone.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"Didone\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Lorenzo Didon\u00e8<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Virtual experiments and Digital-metrological Twins in Coordinate Metrology<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/11\/ghinatti-1.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"ghinatti\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Edoardo Ghinatti<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Production and machining of lightweight alloys and metal matrix composites<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/12\/guarise.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"guarise\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Alessandra Guarise<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Environmental and energy sustainability of manufacturing processes using environmentally friendly lubricants in the Shape Memory Alloy study<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/10\/cropped-ThiagoLF_Foto.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"cropped-ThiagoLF_Foto.jpg\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Thiago, Linhares Fernandes<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Enabling Industry 4.0 by fast and accurate CT metrology\n<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/10\/cropped-Kai-Liu.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"cropped-Kai-Liu.jpg\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Kai Liu<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Manufacturing of microstructured surfaces for advanced functionality<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/11\/Maciariello.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"Maciariello\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Francesco Maciariello<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Physical foaming of sustainable thermoplastic elastomers<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/10\/cropped-Andrea-1-scaled-1.jpeg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"Andrea (1)\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Andrea Pieressa<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Development of digital twins to increase the efficiency and sustainability of the injection molding process<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/10\/cropped-Foto_Javier-scaled-1.jpeg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"Foto_Javier\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Javier, S\u00e1nchez Prieto\n<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">CT-based adaptive advanced manufacturing and assembly<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/11\/Mioli.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"Mioli\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Filippo Mioli<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Zero-Defect Additive Manufacturing process chains enabled by Integrated Metrology<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><div class=\"col-xs-12 col-sm-6 col-md-3\"> <div class=\"card no-padding\"> <img decoding=\"async\" class=\"face\" src=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/12\/Pozzato.jpg\" data-gramm=\"false\" data-quillbot-element=\"L8yT9FNzBZkPsWpQI_vhC\" title=\"Pozzato\" alt=\"\"> <div data-type=\"column\" class=\"col-padding-small col-padding-small-xs description-container\"> <h4 class=\"font-500\" data-gramm=\"false\" data-quillbot-element=\"je3pX42WlEXq9KXMeqpnS\">Nicola Pozzato<\/h4> <p class=\"small\" style=\"font-style: italic\" data-gramm=\"false\" data-quillbot-element=\"pmedZNSgqXQsRnpYPBbJX\">Latest generation inserts to improve machining performance of nickel-based superalloys for aerospace applications<\/p> <div class=\"social-icons-group\" data-type=\"group\"> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-facebook-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-twitter-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-linkedin-square gray\"><\/i><\/a> <a href=\"#\" target=\"_self\" data-reiki-hidden=\"true\" rel=\"noopener\"><i class=\"fa icon fa-google-plus-square gray\"><\/i><\/a><\/div> <\/div><\/div> <\/div><\/div> <\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>PhD Students Ali&nbsp;Beigzadeh New technologies for smart and innovative production systems and materials Nicol\u00f2 Bonato Enabling quality-enhanced advanced manufacturing by innovative metrological solutions Kristal Bornilo Development of silicone-free prefilled plastic syringes by compression moulding of micro-structured surfaces Anna Bortoletto Upcycling di polipropilene da raccolta differenziata urbana in una nuova generazione di compound ad alte prestazioni&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/\">Leggi tutto<\/a><\/p>\n","protected":false},"author":45,"featured_media":548,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pro\/page-templates\/full-width-page.php","meta":{"footnotes":""},"folder":[],"class_list":["post-654","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Research Fellows and PhD St - TECNO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Research Fellows and PhD St - TECNO\" \/>\n<meta property=\"og:description\" content=\"PhD Students Ali&nbsp;Beigzadeh New technologies for smart and innovative production systems and materials Nicol\u00f2 Bonato Enabling quality-enhanced advanced manufacturing by innovative metrological solutions Kristal Bornilo Development of silicone-free prefilled plastic syringes by compression moulding of micro-structured surfaces Anna Bortoletto Upcycling di polipropilene da raccolta differenziata urbana in una nuova generazione di compound ad alte prestazioni&hellip; Leggi tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/\" \/>\n<meta property=\"og:site_name\" content=\"TECNO\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T14:03:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2019\/10\/People_BG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/research-fellows-and-phd-st\\\/\",\"url\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/research-fellows-and-phd-st\\\/\",\"name\":\"Research Fellows and PhD St - TECNO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/research-fellows-and-phd-st\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/research-fellows-and-phd-st\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/10\\\/People_BG.jpg\",\"datePublished\":\"2019-10-23T14:26:01+00:00\",\"dateModified\":\"2023-12-20T14:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/research-fellows-and-phd-st\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/research-fellows-and-phd-st\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/research-fellows-and-phd-st\\\/#primaryimage\",\"url\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/10\\\/People_BG.jpg\",\"contentUrl\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/10\\\/People_BG.jpg\",\"width\":1920,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/research-fellows-and-phd-st\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Research Fellows and PhD St\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/#website\",\"url\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/\",\"name\":\"TECNO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/#organization\",\"name\":\"Universit\u00e0 degli studi di Padova\",\"url\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/12\\\/LOGO_2.png\",\"contentUrl\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/12\\\/LOGO_2.png\",\"width\":5197,\"height\":1890,\"caption\":\"Universit\u00e0 degli studi di Padova\"},\"image\":{\"@id\":\"https:\\\/\\\/research.dii.unipd.it\\\/tecno\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Research Fellows and PhD St - TECNO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/","og_locale":"it_IT","og_type":"article","og_title":"Research Fellows and PhD St - TECNO","og_description":"PhD Students Ali&nbsp;Beigzadeh New technologies for smart and innovative production systems and materials Nicol\u00f2 Bonato Enabling quality-enhanced advanced manufacturing by innovative metrological solutions Kristal Bornilo Development of silicone-free prefilled plastic syringes by compression moulding of micro-structured surfaces Anna Bortoletto Upcycling di polipropilene da raccolta differenziata urbana in una nuova generazione di compound ad alte prestazioni&hellip; Leggi tutto","og_url":"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/","og_site_name":"TECNO","article_modified_time":"2023-12-20T14:03:38+00:00","og_image":[{"width":1920,"height":720,"url":"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2019\/10\/People_BG.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/","url":"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/","name":"Research Fellows and PhD St - TECNO","isPartOf":{"@id":"https:\/\/research.dii.unipd.it\/tecno\/#website"},"primaryImageOfPage":{"@id":"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/#primaryimage"},"image":{"@id":"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/#primaryimage"},"thumbnailUrl":"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2019\/10\/People_BG.jpg","datePublished":"2019-10-23T14:26:01+00:00","dateModified":"2023-12-20T14:03:38+00:00","breadcrumb":{"@id":"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/#primaryimage","url":"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2019\/10\/People_BG.jpg","contentUrl":"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2019\/10\/People_BG.jpg","width":1920,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/research.dii.unipd.it\/tecno\/research-fellows-and-phd-st\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/research.dii.unipd.it\/tecno\/"},{"@type":"ListItem","position":2,"name":"Research Fellows and PhD St"}]},{"@type":"WebSite","@id":"https:\/\/research.dii.unipd.it\/tecno\/#website","url":"https:\/\/research.dii.unipd.it\/tecno\/","name":"TECNO","description":"","publisher":{"@id":"https:\/\/research.dii.unipd.it\/tecno\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/research.dii.unipd.it\/tecno\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/research.dii.unipd.it\/tecno\/#organization","name":"Universit\u00e0 degli studi di Padova","url":"https:\/\/research.dii.unipd.it\/tecno\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/research.dii.unipd.it\/tecno\/#\/schema\/logo\/image\/","url":"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/12\/LOGO_2.png","contentUrl":"https:\/\/research.dii.unipd.it\/tecno\/wp-content\/uploads\/sites\/22\/2023\/12\/LOGO_2.png","width":5197,"height":1890,"caption":"Universit\u00e0 degli studi di Padova"},"image":{"@id":"https:\/\/research.dii.unipd.it\/tecno\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/research.dii.unipd.it\/tecno\/wp-json\/wp\/v2\/pages\/654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.dii.unipd.it\/tecno\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/research.dii.unipd.it\/tecno\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/research.dii.unipd.it\/tecno\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/research.dii.unipd.it\/tecno\/wp-json\/wp\/v2\/comments?post=654"}],"version-history":[{"count":14,"href":"https:\/\/research.dii.unipd.it\/tecno\/wp-json\/wp\/v2\/pages\/654\/revisions"}],"predecessor-version":[{"id":1556,"href":"https:\/\/research.dii.unipd.it\/tecno\/wp-json\/wp\/v2\/pages\/654\/revisions\/1556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/research.dii.unipd.it\/tecno\/wp-json\/wp\/v2\/media\/548"}],"wp:attachment":[{"href":"https:\/\/research.dii.unipd.it\/tecno\/wp-json\/wp\/v2\/media?parent=654"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/research.dii.unipd.it\/tecno\/wp-json\/wp\/v2\/folder?post=654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}